{"id":14134,"date":"2024-07-01T23:50:26","date_gmt":"2024-07-02T06:50:26","guid":{"rendered":"https:\/\/sonomalandtrust.org\/blog\/julio-2024-enews\/"},"modified":"2024-07-01T23:50:26","modified_gmt":"2024-07-02T06:50:26","slug":"julio-2024-enews","status":"publish","type":"post","link":"https:\/\/sonomalandtrust.org\/es\/blog\/julio-2024-enews\/","title":{"rendered":"Julio 2024 eNews"},"content":{"rendered":"<div id=\"ConservationCouncil\"><\/div>\n<h2>Lo que dicen hoy los cient\u00edficos del ma\u00f1ana<\/h2>\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/www.youtube.com\/watch?v=tKSePBQHHdI\"><img decoding=\"async\" src=\"https:\/\/sonomalandtrust.org\/wp-content\/uploads\/2024\/07\/SLT_eNews_July_2024_CC_B-scaled.jpg\" alt=\"\"><\/a><\/figure>\n<p><span data-contrast=\"none\">El programa para adolescentes del Consejo de Conservaci\u00f3n de Sonoma Land Trust est\u00e1 dando pasos importantes en la formaci\u00f3n de la pr\u00f3xima generaci\u00f3n de l\u00edderes medioambientales. La caracter\u00edstica distintiva del programa es su investigaci\u00f3n pr\u00e1ctica dirigida por j\u00f3venes en nuestras reservas ecol\u00f3gicas, combinada con una educaci\u00f3n en profundidad sobre las v\u00edas que conducen a carreras en STEM y conservaci\u00f3n. Los participantes adquieren las habilidades, los conocimientos y la pasi\u00f3n necesarios para marcar una diferencia tangible en sus comunidades y m\u00e1s all\u00e1.  <\/span><\/p>\n<p><a href=\"https:\/\/sonomalandtrust.org\/from-conservation-council-to-columbia-a-scholars-journey-in-environmental-sciences\/\"><span data-contrast=\"none\"><img decoding=\"async\" class=\"alignleft size-medium wp-image-38912\" src=\"https:\/\/sonomalandtrust.org\/wp-content\/uploads\/2024\/07\/bertha_headshot-225x300.jpg\" alt=\"\" width=\"225\" height=\"300\">Lee sobre Bertha Saucedo<\/span><\/a><span data-contrast=\"none\">: Estudiante destacada y graduada del Consejo de Conservaci\u00f3n 2024, fue entrevistada sobre su experiencia con el programa y c\u00f3mo llev\u00f3 esa experiencia hasta la Universidad de Columbia para estudiar qu\u00edmica medioambiental. <\/span> <\/p>\n<p><span data-contrast=\"none\">Puntos destacados del Programa del Consejo de Conservaci\u00f3n:<\/span><br \/>\n<b><span data-contrast=\"none\">Aprendizaje pr\u00e1ctico:<\/span><\/b><span data-contrast=\"none\"> Los participantes adolescentes participan en actividades de conservaci\u00f3n del mundo real, desde la restauraci\u00f3n de h\u00e1bitats hasta la gesti\u00f3n sostenible de la tierra, lo que les proporciona habilidades tangibles que podr\u00e1n llevar consigo a la universidad y m\u00e1s all\u00e1. Aprenden a realizar investigaciones de campo, que pueden incluir la instalaci\u00f3n y supervisi\u00f3n de c\u00e1maras de fauna, la catalogaci\u00f3n de los datos actuales y su incorporaci\u00f3n a otras fuentes de datos para crear un conocimiento exhaustivo de las especies que est\u00e1n investigando. Terminan el a\u00f1o publicando la investigaci\u00f3n cient\u00edfica en art\u00edculos y carteles, que presentan en una exposici\u00f3n a la que asisten sus compa\u00f1eros, familiares, personal del fideicomiso de tierras y miembros de la comunidad para compartir sus hallazgos sobre las pr\u00e1cticas de gesti\u00f3n de tierras en reservas ecol\u00f3gicas.<\/span><\/p>\n<p><b><span data-contrast=\"none\">Talleres Educativos:<\/span><\/b><span data-contrast=\"none\"> El programa ofrece una serie de talleres interactivos que abarcan temas como la \u00e9tica al aire libre y la Cosecha Honrosa, el m\u00e9todo cient\u00edfico, la conservaci\u00f3n de la vida salvaje, las pr\u00e1cticas sostenibles y la importancia de conservar los paisajes naturales. Las excursiones a laboratorios cient\u00edficos como el Laboratorio Marino de Bodega y el campus universitario de UC Davis aumentan su formaci\u00f3n con expertos en la materia que pueden responder a sus preguntas y ofrecerles m\u00e1s orientaci\u00f3n adaptada a su proyecto de investigaci\u00f3n.<\/span><\/p>\n<p><b><span data-contrast=\"none\">Compromiso con la comunidad:<\/span><\/b><span data-contrast=\"none\"> Al fomentar el sentido de la responsabilidad medioambiental, el programa anima a los j\u00f3venes a desempe\u00f1ar un papel activo en sus comunidades, promoviendo una cultura de administraci\u00f3n y conservaci\u00f3n. Los miembros se grad\u00faan con una conexi\u00f3n m\u00e1s profunda consigo mismos, con sus compa\u00f1eros y con el gran campo de las ciencias medioambientales.<\/span><\/p>\n<p><b><span data-contrast=\"auto\">Trayectorias profesionales: <\/span><\/b>Los miembros del Consejo de Conservaci\u00f3n participan en una Exposici\u00f3n de Carreras Profesionales organizada por la Fundaci\u00f3n para la Tierra de Sonoma y el Comit\u00e9 de Desarrollo Juvenil de la Colaboraci\u00f3n para la Educaci\u00f3n Medioambiental de Sonoma (SEEC), donde se informan sobre la amplia gama de oportunidades en el \u00e1mbito de la ciencia y la conservaci\u00f3n. Se les proporciona ayuda individualizada para elaborar su curr\u00edculum estudiantil para las solicitudes universitarias y se les da acceso a una comunidad Discord personalizada creada por los l\u00edderes del programa Sonoma Land Trust que incluye una base de conocimientos sobre programas de educaci\u00f3n superior, recursos financieros y art\u00edculos sobre c\u00f3mo seguir una carrera que les interese. <\/p>\n<p><b>El programa est\u00e1 recibiendo buenas calificaciones:<\/b><\/p>\n<p><b><span data-contrast=\"auto\">Los graduados de 2020-2023 que fueron encuestados compartieron:<\/span><\/b><\/p>\n<ul>\n<li><span data-contrast=\"none\">El 100% dijo que ten\u00eda un mayor conocimiento de las carreras STEM<\/span><\/li>\n<li>80% Creen que pueden ser cient\u00edficos o conservacionistas si quieren<\/li>\n<li>el 75% aument\u00f3 su probabilidad de seguir una carrera en conservaci\u00f3n, otros ya sab\u00edan a qu\u00e9 quer\u00edan dedicarse o decidieron que no era para ellos<\/li>\n<li>100% Aprendi\u00f3 sobre las tierras protegidas y su importancia<\/li>\n<li>El 91% aument\u00f3 su inter\u00e9s por la ciencia y la conservaci\u00f3n<\/li>\n<li>El 73% comprende mejor las v\u00edas para convertirse en conservacionista y\/o profesional STEM<\/li>\n<\/ul>\n<p><b><span data-contrast=\"none\">Se a\u00f1ade la clase de 2024:<\/span><\/b><\/p>\n<ul>\n<li><span data-contrast=\"none\">100% &#8211; comprender mejor las v\u00edas para convertirse en conservacionista y\/o profesional STEM<\/span><\/li>\n<li>El 89% aprendi\u00f3 sobre STEM o una carrera de conservaci\u00f3n que les interesaba<\/li>\n<\/ul>\n<figure class=\"wp-block-image size-large\"><\/figure>\n<hr class=\"wp-block-separator\">\n<div id=\"Familias\"><\/div>\n<h2>Reunir a las familias, en la naturaleza<\/h2>\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" src=\"https:\/\/sonomalandtrust.org\/wp-content\/uploads\/2024\/07\/SLT_eNews_July_2024_Familias.jpg\" alt=\"\"><\/figure>\n<p><span data-contrast=\"auto\">Celebramos el quinto aniversario del programa biling\u00fce de Sonoma Land Trust <\/span><i><span data-contrast=\"auto\">Familias al Aire Libre<\/span><\/i><span data-contrast=\"auto\"> con actividades y lugares renovados y una mayor capacidad para llevar a m\u00e1s familias al aire libre. Lo que sigue siendo lo mismo es el coraz\u00f3n del programa: explorar la biodiversidad del condado de Sonoma con una comunidad de amigos y familias.<\/span><span data-ccp-props=\"{\"134233117\":false,\"134233118\":false,\"201341983\":0,\"335559685\":0,\"335559738\":0,\"335559739\":160,\"335559740\":257}\"> <\/span><\/p>\n<p><span data-contrast=\"auto\">El cuarto s\u00e1bado de cada mes, las familias se re\u00fanen en la oficina del Sonoma Land Trust, se suben a una furgoneta de transporte y parten hacia un parque p\u00fablico o terreno protegido para pasar un d\u00eda de exploraci\u00f3n de la naturaleza y actividades divertidas e inclusivas para ni\u00f1os de todas las edades. Estas salidas gratuitas se organizan en espa\u00f1ol y se traducen al ingl\u00e9s, satisfaciendo una necesidad local de m\u00e1s experiencias guiadas en la naturaleza dedicadas a las familias latinas y dise\u00f1adas pensando en ellas. <\/span><span data-ccp-props=\"{\"134233117\":false,\"134233118\":false,\"201341983\":0,\"335559685\":0,\"335559738\":0,\"335559739\":160,\"335559740\":257}\"> <\/span><\/p>\n<p><span data-contrast=\"auto\">Para los ni\u00f1os, la conexi\u00f3n con la naturaleza va mucho m\u00e1s all\u00e1 de cultivar la pr\u00f3xima generaci\u00f3n de guardianes del medio ambiente. Pasar tiempo al aire libre tiene muchos beneficios para el desarrollo, como la mejora de la salud f\u00edsica y mental, el aumento de la creatividad y la imaginaci\u00f3n, la mejora de la atenci\u00f3n y la concentraci\u00f3n, el desarrollo de habilidades sociales y sensoriales, y mucho m\u00e1s. Recrearse juntos en la naturaleza es una forma de que las familias y las comunidades se unan, pero el acceso al aire libre no siempre es igualitario. Una barrera importante para el ocio guiado al aire libre es el idioma, que <\/span><i><span data-contrast=\"auto\">Familias al Aire Libre <\/span><\/i><span data-contrast=\"auto\">pretende remediar.<\/span><span data-ccp-props=\"{\"134233117\":false,\"134233118\":false,\"201341983\":0,\"335559685\":0,\"335559738\":0,\"335559739\":160,\"335559740\":257}\"> <\/span><\/p>\n<p><b><span data-contrast=\"auto\">Un esfuerzo de colaboraci\u00f3n para la comunidad<\/span><\/b><span data-ccp-props=\"{\"134233118\":false,\"201341983\":0,\"335559685\":0,\"335559739\":160,\"335559740\":257}\"> <\/span><\/p>\n<p><span data-contrast=\"auto\">Sonoma Land Trust puso en marcha el programa biling\u00fce en abril de 2019 en colaboraci\u00f3n con V\u00eda Esperanza, el centro de recursos familiares de Community Action Network (CAN). La Directora de Programas P\u00fablicos, Ingrid Stearns, destac\u00f3 el importante papel que desempe\u00f1\u00f3 el anterior Director de Programas de V\u00eda Esperanza, Mike Varela.<\/span><span data-contrast=\"auto\">,<\/span><span data-contrast=\"auto\"> y la organizaci\u00f3n en el lanzamiento del programa: \u00abSeguimos su ejemplo en el dise\u00f1o del programa, y se pusieron en contacto con los participantes de su programa actual para que se unieran a nosotros en las excursiones mensuales\u00bb. Los beneficios de la programaci\u00f3n biling\u00fce se vieron de inmediato, e Ingrid comparti\u00f3: \u00abSi hacemos las presentaciones en espa\u00f1ol, mucha m\u00e1s gente participa en los debates y hace preguntas\u00bb. <\/span> <span data-ccp-props=\"{\"134233117\":false,\"134233118\":false,\"201341983\":0,\"335551550\":1,\"335551620\":1,\"335559685\":0,\"335559737\":0,\"335559738\":0,\"335559739\":160,\"335559740\":257}\"> <\/span><\/p>\n<p><span data-contrast=\"auto\">Al cabo de cuatro meses, Varela se traslad\u00f3 fuera de la zona y Sonoma Land Trust se esforz\u00f3 por mantener el programa. Sin embargo, poco despu\u00e9s comenz\u00f3 la pandemia del COVID-19 y la programaci\u00f3n en persona, incluidas las salidas, se vio obligada a interrumpirse. Para no perder el impulso de un programa incipiente, conseguimos el apoyo de Luz Huerta, apasionada amante de la naturaleza y organizadora del Grupo de Juego Pasitos de CAN, un programa para padres e hijos centrado en la preparaci\u00f3n para el \u00e9xito en la guarder\u00eda y m\u00e1s all\u00e1. Ella contribuy\u00f3 decisivamente a mantener el programa en marcha durante la pandemia y a convertirlo en lo que es hoy; Luz trabaj\u00f3 para organizar a los participantes de una de nuestras primeras excursiones virtuales en espa\u00f1ol en 2022 y apoy\u00f3 el relanzamiento de las salidas en persona una vez que fue seguro volver a hacerlo.   <\/span><span data-ccp-props=\"{\"134233118\":false,\"201341983\":0,\"335559685\":0,\"335559739\":160,\"335559740\":257}\"> <\/span><\/p>\n<p><span data-contrast=\"auto\">Su dedicaci\u00f3n a establecer conexiones con la naturaleza va m\u00e1s all\u00e1 de su funci\u00f3n profesional y forma parte de qui\u00e9n es. Luz adora el condado de Sonoma, y comparti\u00f3 que \u00abse siente bendecida por vivir en este lugar rodeada de bellos paisajes y lugares [que] nunca habr\u00eda imaginado que existieran\u00bb. Ella y su marido Cornelio dieron prioridad a pasar tiempo con sus hijos juntos en la naturaleza, citando esto como una de las razones por las que hoy en d\u00eda sienten un gran amor por el aire libre. Su hijo Daniel disfruta plantando su propia fruta y verdura en el huerto comunitario, y su hija Leslie, antigua miembro del Consejo de Conservaci\u00f3n del Sonoma Land Trust, estudia ahora zoolog\u00eda y ciencias medioambientales en la universidad.   <\/span><span data-ccp-props=\"{\"134233118\":false,\"201341983\":0,\"335559685\":0,\"335559739\":160,\"335559740\":257}\"> <\/span><\/p>\n<p><span data-contrast=\"auto\">En marzo de este a\u00f1o, Carlos Rivas se incorpor\u00f3 a Sonoma Land Trust como nuevo Coordinador de Salidas. Ha aportado nueva energ\u00eda a <\/span><i><span data-contrast=\"auto\">Familias al Aire Libre <\/span><\/i><span data-contrast=\"auto\">revitaliz\u00e1ndolo con su amplia experiencia en educaci\u00f3n juvenil al aire libre, sus conocimientos ling\u00fc\u00edsticos biling\u00fces, su compromiso con la comunidad y su pasi\u00f3n personal por compartir la naturaleza con los dem\u00e1s, especialmente con su hijo peque\u00f1o. <\/span> <span data-ccp-props=\"{\"134233118\":false,\"201341983\":0,\"335559685\":0,\"335559739\":160,\"335559740\":257}\"> <\/span><\/p>\n<p><b><span data-contrast=\"auto\">Compartir una pasi\u00f3n entre generaciones<\/span><\/b><span data-ccp-props=\"{\"134233118\":false,\"201341983\":0,\"335559685\":0,\"335559739\":160,\"335559740\":257}\"> <\/span><\/p>\n<p><span data-contrast=\"auto\">Familias al Aire Libre es m\u00e1s que salidas mensuales, es un espacio acogedor al que las familias vuelven una y otra vez. <\/span><span data-contrast=\"none\">La familia de H\u00e9ctor Camacho<\/span><span data-contrast=\"auto\"> y Lucy D\u00edaz conocieron el programa a trav\u00e9s de la participaci\u00f3n de su hijo H\u00e9ctor en el programa Pasitos. Conocieron a Carlos cuando vino a clase a presentarles el programa de salidas biling\u00fces, e inmediatamente se apuntaron, compartiendo que \u00abha sido maravilloso desde el primer momento\u00bb.<\/span><span data-ccp-props=\"{\"134233118\":false,\"201341983\":0,\"335559685\":0,\"335559739\":160,\"335559740\":257}\"> <\/span><\/p>\n<p><span data-contrast=\"auto\">Lucy dice que las salidas de Familias al Aire Libre dan a su familia la oportunidad de tomarse un respiro y pasar tiempo de calidad juntos, algo que no ocurre a menudo con los muchos compromisos y actividades de la vida cotidiana. <\/span><span data-contrast=\"none\">H\u00e9ctor<\/span><span data-contrast=\"auto\"> y Lucy, ambos nacidos en el estado de Michoac\u00e1n, M\u00e9xico, comparten un amor por la naturaleza que comenz\u00f3 en la infancia. La pareja ha visto c\u00f3mo esto se ha transmitido a sus hijos a medida que han ido creciendo, no s\u00f3lo en <\/span><span data-contrast=\"none\">H\u00e9ctor<\/span><span data-contrast=\"auto\"> (5), sino tambi\u00e9n en Bricia (10), Ailinn (18) y Daniel (22). <\/span> <span data-ccp-props=\"{\"134233118\":false,\"201341983\":0,\"335559685\":0,\"335559739\":160,\"335559740\":257}\"> <\/span><\/p>\n<p><span data-contrast=\"auto\">El aspecto comunitario del programa hace que <\/span><span data-contrast=\"none\">H\u00e9ctor y la familia de Lucy se sientan bienvenidos y c\u00f3modos, y siempre les entusiasma aprender algo con el equipo de Sonoma Land Trust, ya sea un nuevo animal o insecto que observar o una actividad como pintar con arcilla.<\/span> <span data-contrast=\"none\">H\u00e9ctor<\/span><span data-contrast=\"auto\"> y Lucy han visto a sus hijos \u00abesperando el momento de sentirse libres en la naturaleza\u00bb, y Bricia comparte: \u00abMe encanta sentir el viento. Prefiero estar en la naturaleza que jugando con mis juguetes\u00bb.<\/span><span data-ccp-props=\"{\"134233118\":false,\"201341983\":0,\"335559685\":0,\"335559739\":160,\"335559740\":257}\"> <\/span><\/p>\n<p><span data-contrast=\"auto\">Sonoma Land Trust crea programas que refuerzan la conexi\u00f3n de la comunidad con la naturaleza y entre s\u00ed. M\u00e1s informaci\u00f3n sobre <\/span><a href=\"https:\/\/sonomalandtrust.org\/outings\/families-outdoors\/\"><span data-contrast=\"none\">Familias al Aire Libre en nuestro sitio web<\/span><\/a><span data-contrast=\"auto\">.<\/span><\/p>\n<hr class=\"wp-block-separator\">\n<div id=\"Familias-spanish\"><\/div>\n<h2><\/h2>\n<div id=\"MilesHorton\"><\/div>\n<h2>Una Fuerza de la Naturaleza en el punto de mira: Miles Horton<\/h2>\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" src=\"https:\/\/sonomalandtrust.org\/wp-content\/uploads\/2024\/07\/SLT_eNews_July_2024_Miles.jpg\" alt=\"\"><\/figure>\n<p><span data-contrast=\"auto\">Miles Horton se sinti\u00f3 atra\u00eddo por el condado de Sonoma por una raz\u00f3n que muchos compartimos: el acceso al aire libre. \u00abQuer\u00eda estar en un lugar donde pudiera salir por la puerta y estar en un sendero, corriendo, haciendo senderismo o yendo a la playa<\/span><span data-contrast=\"none\">explic\u00f3.<\/span><span data-contrast=\"auto\"> Miles se traslad\u00f3 a Santa Rosa desde Sacramento en diciembre del a\u00f1o pasado, tras siete a\u00f1os trabajando en pol\u00edtica en el Capitolio. Se describe a s\u00ed mismo como un \u00abfan\u00e1tico observador de aves\u00bb y nos cuenta que el tiempo que ha pasado aqu\u00ed hasta ahora \u00abha sido incre\u00edble, explorando nuestros terrenos p\u00fablicos locales, como el Parque Estatal Trione-Annadel y el Parque Regional Taylor Mountain, y avistando especies de aves que llevaban tiempo en [su] lista\u00bb.<\/span><span data-ccp-props=\"{\"134233117\":false,\"134233118\":false,\"201341983\":0,\"335559738\":0,\"335559739\":160,\"335559740\":257}\"> <\/span><\/p>\n<p><span data-contrast=\"auto\">Miles conoci\u00f3 Sonoma Land Trust a trav\u00e9s de nuestra labor de defensa en el Capitolio del Estado. Trabajando para el Portavoz de la Asamblea, Robert Rivas, que apoya la pol\u00edtica en materia de conservaci\u00f3n, cambio clim\u00e1tico y tierras de labor naturales, vio de primera mano la importancia de este trabajo. El a\u00f1o pasado, Gymmel Trembly, antiguo miembro del consejo de Land Trust, le present\u00f3 formalmente la organizaci\u00f3n y le invit\u00f3 a un acto informativo en Petaluma.  <\/span><span data-ccp-props=\"{\"134233117\":false,\"134233118\":false,\"201341983\":0,\"335559738\":0,\"335559739\":160,\"335559740\":257}\"> <\/span><\/p>\n<p><span data-contrast=\"auto\">Miles consideraba que gran parte de la pol\u00edtica de conservaci\u00f3n que ve\u00eda en Sacramento carec\u00eda de un siguiente paso fundamental: c\u00f3mo se gestionar\u00eda la tierra que se estaba protegiendo para que resistiera al cambio clim\u00e1tico. Miles asisti\u00f3 recientemente a una excursi\u00f3n de Sonoma Land Trust a la Bah\u00eda de San Pablo, donde conoci\u00f3 a algunos miembros de nuestro equipo y aprendi\u00f3 sobre pr\u00e1cticas de gesti\u00f3n de tierras como la restauraci\u00f3n de humedales para combatir la subida del nivel del mar, que en su opini\u00f3n faltaban a menudo en la pol\u00edtica estatal. <\/span><span data-ccp-props=\"{\"134233117\":false,\"134233118\":false,\"201341983\":0,\"335559738\":0,\"335559739\":160,\"335559740\":257}\"> <\/span><\/p>\n<p><span data-contrast=\"auto\">Adem\u00e1s de que sus aficiones y valores personales coinciden con la misi\u00f3n de Sonoma Land Trust, la carrera profesional de Miles se cruza con el trabajo que hacemos. Es Director de Pol\u00edtica Legislativa y Participaci\u00f3n Comunitaria de Sonoma Clean Power, y se sinti\u00f3 atra\u00eddo por la organizaci\u00f3n como joven profesional que buscaba tener un impacto en su comunidad porque no s\u00f3lo proporciona energ\u00eda limpia al condado de Sonoma, sino que tambi\u00e9n sirve como veh\u00edculo para promulgar las prioridades clim\u00e1ticas locales.   <\/span><span data-ccp-props=\"{\"134233117\":false,\"134233118\":false,\"201341983\":0,\"335559738\":0,\"335559739\":160,\"335559740\":257}\"> <\/span><\/p>\n<p><span data-contrast=\"auto\">Sonoma Clean Power suministra actualmente m\u00e1s del 90% de energ\u00eda limpia a sus clientes, y est\u00e1n trabajando duro para cerrar la brecha de ese \u00faltimo 10% a trav\u00e9s de su nueva <\/span><a href=\"https:\/\/sonomacleanpower.org\/geozone\"><span data-contrast=\"none\">iniciativa GeoZone<\/span><\/a><span data-contrast=\"auto\">un proyecto que entusiasma especialmente a Miles. Explica: \u00abEsta &#8216;pr\u00f3xima generaci\u00f3n&#8217; de energ\u00eda geot\u00e9rmica puede funcionar las veinticuatro horas del d\u00eda, es resistente frente a olas de calor y cat\u00e1strofes naturales, utiliza mucha menos agua que la energ\u00eda geot\u00e9rmica convencional y tiene una huella mucho menor que la energ\u00eda solar o e\u00f3lica\u00bb, preservando la rica biodiversidad y los paisajes del condado de Sonoma.<\/span><span data-ccp-props=\"{\"134233117\":false,\"134233118\":false,\"201341983\":0,\"335559738\":0,\"335559739\":160,\"335559740\":257}\"> <\/span><\/p>\n<p><span data-contrast=\"auto\">Adem\u00e1s de trabajar en proyectos de ley sobre energ\u00eda limpia y clima, Miles interact\u00faa con la comunidad en relaci\u00f3n con proyectos como GeoZone, respondiendo a preguntas, reuni\u00e9ndose con organizaciones y grupos comunitarios para conocer sus opiniones y sentar las bases de la colaboraci\u00f3n, y asegur\u00e1ndose de que los beneficios sean locales, como la creaci\u00f3n de puestos de trabajo altamente cualificados y bien pagados, que sean estables incluso cuando fluct\u00faen los mercados energ\u00e9ticos mundiales. La misi\u00f3n de SCP es combatir el cambio clim\u00e1tico, y est\u00e1n estudiando qu\u00e9 pueden hacer para tener un impacto m\u00e1s amplio m\u00e1s all\u00e1 del condado de Sonoma, con la esperanza de que esta nueva tecnolog\u00eda de energ\u00eda limpia acabe adopt\u00e1ndose en todo el mundo. <\/span><span data-ccp-props=\"{\"134233117\":false,\"134233118\":false,\"201341983\":0,\"335559738\":0,\"335559739\":160,\"335559740\":257}\"> <\/span><\/p>\n<p><span data-contrast=\"auto\">Miles es miembro de Sonoma Land Trust porque le impresiona nuestro enfoque para afrontar el doble reto del cambio clim\u00e1tico y la p\u00e9rdida de biodiversidad. Aprecia que el Land Trust est\u00e9 \u00absaliendo y haciendo\u00bb el trabajo, meti\u00e9ndose de lleno en la adopci\u00f3n de medidas audaces y r\u00e1pidas para abordar estos problemas y \u00aballanando el camino\u00bb hacia la gesti\u00f3n de las tierras para la resiliencia clim\u00e1tica. Est\u00e1 asombrado por la comunidad del condado de Sonoma, por el amor y el cuidado compartidos por el aire libre, la conservaci\u00f3n y la administraci\u00f3n, y le entusiasma formar parte de ella.  <\/span><\/p>\n<hr class=\"wp-block-separator\">\n<div id=\"GoodFireNotification\"><\/div>\n<h2>Buena Notificaci\u00f3n de Incendios<\/h2>\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" src=\"https:\/\/sonomalandtrust.org\/wp-content\/uploads\/2024\/07\/SLT_eNews_July_2024_GoodFire-scaled.jpg\" alt=\"\"><\/figure>\n<p><span data-contrast=\"auto\">Las quemas prescritas son una forma de restaurar nuestros ecosistemas naturales, y para nosotros es importante mantener informada a nuestra comunidad. Antes de cada quema, colocamos avisos en las carreteras, nos ponemos en contacto con los vecinos adyacentes, publicamos alertas en las redes sociales y en la aplicaci\u00f3n Watchduty, y emitimos comunicados de prensa con detalles y mapas. <\/span><span data-ccp-props=\"{\"134233117\":false,\"134233118\":false,\"201341983\":0,\"335551550\":1,\"335551620\":1,\"335559685\":0,\"335559737\":0,\"335559738\":150,\"335559739\":330,\"335559740\":259}\"> <\/span><\/p>\n<p><span data-contrast=\"auto\">Ahora puedes recibir directamente en tu bandeja de entrada notificaciones sobre el humo de las quemas prescritas realizadas en las propiedades de la Fundaci\u00f3n para las Tierras de Sonoma. <\/span><a href=\"https:\/\/sonomalandtrust.org\/prescribed-fire-alert\/\"><span data-contrast=\"none\">M\u00e1s informaci\u00f3n e inscr\u00edbete aqu\u00ed<\/span><\/a><span data-contrast=\"auto\">.<\/span><\/p>\n<hr class=\"wp-block-separator\">\n<div id=\"AFFNConclusion\"><\/div>\n<h2>Una fuerza de la naturaleza<\/h2>\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/sonomalandtrust.org\/a-force-for-nature#campaign-video\"><img decoding=\"async\" src=\"https:\/\/sonomalandtrust.org\/wp-content\/uploads\/2024\/07\/SLT_eNews_July_2024_AFFN_Alt-scaled.jpg\" alt=\"\"><\/a><\/figure>\n<p><span data-contrast=\"auto\">\u00a1Gracias por ser Una Fuerza de la Naturaleza! Estamos muy agradecidos por tu apoyo durante los seis \u00faltimos a\u00f1os de esta campa\u00f1a. Tu generosidad nos ha permitido financiar la conservaci\u00f3n de la tierra y los recursos naturales y prepararnos para los impactos de un clima cambiante. Desde el lanzamiento de la campa\u00f1a en 2018, miles de personas se unieron para apoyar el trabajo de nuestro plan estrat\u00e9gico: proteger casi 9.000 acres y completar 14 impactantes proyectos de conservaci\u00f3n para garantizar que la tierra, las personas y el agua del condado de Sonoma puedan prosperar.   <\/span><span data-ccp-props=\"{\"134233117\":false,\"134233118\":false,\"201341983\":0,\"335551550\":1,\"335551620\":1,\"335559738\":0,\"335559739\":160,\"335559740\":257}\"> <\/span><\/p>\n<p><a href=\"https:\/\/sonomalandtrust.org\/a-force-for-nature\/\"><span class=\"TextRun SCXW209792286 BCX2\" lang=\"EN-US\" data-contrast=\"auto\"><span class=\"NormalTextRun CommentStart CommentHighlightPipeClickedV2 CommentHighlightClicked SCXW209792286 BCX2\">M\u00e1s informaci\u00f3n sobre el impacto de Una Fuerza de la Naturaleza<\/span><\/span><\/a><\/p>\n<hr class=\"wp-block-separator\">\n<div id=\"LotL\"><\/div>\n<h2>El Lenguaje de la Tierra: Arte en el Paisaje<\/h2>\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/sonomalandtrust.zoom.us\/meeting\/register\/tZMkc-2rqjMpGdUqawyKkWaJTzbtxb7f9tMZ\"><img decoding=\"async\" src=\"https:\/\/sonomalandtrust.org\/wp-content\/uploads\/2024\/07\/SLT_eNews_July_2024_LOtL-scaled.jpg\" alt=\"\"><\/a><\/figure>\n<p><span data-contrast=\"auto\">\u00bfCu\u00e1l es una forma de saborear la magn\u00edfica abundancia de paisajes del condado de Sonoma? A trav\u00e9s del arte. Aprender a dibujar o pintar de la naturaleza profundiza nuestra relaci\u00f3n con la tierra. Acomp\u00e1\u00f1anos online en un divertido y l\u00fadico taller de arte con Elizabeth McKoy, del centro de creatividad sin \u00e1nimo de lucro Artaluma, de Petaluma. Ella nos guiar\u00e1 a la hora de poner nuestros l\u00e1pices, bol\u00edgrafos y pinceles sobre el papel para capturar la belleza del aire libre. Este taller estar\u00e1 guiado por el juego y la exploraci\u00f3n, y es para cualquiera y para todos.     <\/span><\/p>\n<p><span data-contrast=\"auto\">Habr\u00e1 interpretaci\u00f3n al espa\u00f1ol.<\/span><\/p>\n<p><a href=\"https:\/\/sonomalandtrust.zoom.us\/meeting\/register\/tZMkc-2rqjMpGdUqawyKkWaJTzbtxb7f9tMZ\">Reg\u00edstrate en<\/a><\/p>\n<hr class=\"wp-block-separator\">\n<div id=\"outings\"><\/div>\n<h2>Salidas gratuitas<\/h2>\n<figure class=\"wp-block-image size-large\"><a href=\"\/outings\"><img decoding=\"async\" src=\"https:\/\/sonomalandtrust.org\/wp-content\/uploads\/2024\/07\/SLT_eNews_July_2024_Outings.jpg\" alt=\"\"><\/a><\/figure>\n<p><span data-contrast=\"auto\">\u00a1\u00danete a nosotros en la naturaleza este mes! Organizaremos una serie de paseos por arroyos urbanos y excursiones al atardecer, as\u00ed como nuestra actividad mensual biling\u00fce <\/span><i><span data-contrast=\"auto\">Familias al Aire Libre\/Families Outdoors<\/span><\/i><span data-contrast=\"auto\"> al Aire Libre. <\/span><a href=\"http:\/\/sonomalandtrust.org\/outings\"><span data-contrast=\"none\">Inf\u00f3rmate e inscr\u00edbete en nuestro sitio web<\/span><\/a><span data-contrast=\"auto\">.<\/span><span data-ccp-props=\"{\"134233117\":false,\"134233118\":false,\"201341983\":0,\"335551550\":1,\"335551620\":1,\"335559738\":0,\"335559739\":240,\"335559740\":259}\"> <\/span><\/p>\n<p><span data-contrast=\"auto\">Muchas de estas excursiones se realizan en colaboraci\u00f3n con Ag + Open Space del condado de Sonoma.<\/span><span data-ccp-props=\"{\"134233117\":false,\"134233118\":false,\"201341983\":0,\"335551550\":1,\"335551620\":1,\"335559738\":240,\"335559739\":240,\"335559740\":259}\"> <\/span><\/p>\n<hr class=\"wp-block-separator\">\n<div id=\"recommendations\"><\/div>\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" src=\"https:\/\/sonomalandtrust.org\/wp-content\/uploads\/2024\/07\/SLT_2024_Recommendation_Ologies.jpg\" alt=\"\"><\/figure>\n<p><span data-contrast=\"auto\">Ologies es un programa cient\u00edfico c\u00f3mico que se sumerge en todo lo que sea \u00ab-olog\u00eda\u00bb con diversos co-presentadores, <\/span><i><span data-contrast=\"auto\">ologistas<\/span><\/i><i><span data-contrast=\"auto\">,<\/span><\/i><span data-contrast=\"auto\"> expertos en sus campos de estudio. Es una forma excelente de re\u00edr y aprender sobre una gran variedad de temas. Las <\/span> <a href=\"https:\/\/www.alieward.com\/smologies\"><i><span data-contrast=\"auto\">smolog\u00edas <\/span><\/i><\/a><span data-contrast=\"auto\">son versiones m\u00e1s cortas aptas para ni\u00f1os. Cada <\/span><i><span data-contrast=\"auto\">ologista <\/span><\/i><span data-contrast=\"auto\">elige una organizaci\u00f3n ben\u00e9fica que recibe una parte de los ingresos publicitarios del podcast. Recomiendo escuchar <\/span>  <span data-contrast=\"auto\"><a href=\"https:\/\/www.alieward.com\/ologies\/foragingecologyencore\">Ecolog\u00eda del forrajeo con Alexis Nikole Nelson (@BlackForager<\/a>), <a href=\"https:\/\/www.alieward.com\/ologies\/ethnoecology\">Etnoecolog\u00eda con Leigh Joseph (Squamish)<\/a>, <a href=\"https:\/\/www.alieward.com\/ologies\/goodfire\">Ecolog\u00eda ind\u00edgena del fuego con la Dra. Amy Christianson (M\u00e9tis)<\/a>, y <a href=\"https:\/\/www.alieward.com\/ologies\/indigenousmelittology?rq=bees\">Melittolog\u00eda nativa (Abejas) con Krystle Hickman<\/a>.<\/span><span data-ccp-props=\"{\"201341983\":0,\"335559739\":160,\"335559740\":259}\"> <\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El programa para adolescentes del Consejo de Conservaci\u00f3n de Sonoma Land Trust est\u00e1 dando pasos importantes en la formaci\u00f3n de la pr\u00f3xima generaci\u00f3n de l\u00edderes medioambientales. La caracter\u00edstica distintiva del programa es su investigaci\u00f3n pr\u00e1ctica dirigida por j\u00f3venes en nuestras reservas ecol\u00f3gicas, combinada con una educaci\u00f3n en profundidad sobre las v\u00edas que conducen a carreras [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":14140,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[85],"tags":[],"class_list":["post-14134","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-enoticias"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Julio 2024 eNews &#8212; Sonoma Land Trust<\/title>\n<meta name=\"description\" content=\"Lo que dicen hoy los cient\u00edficos del ma\u00f1ana El programa para adolescentes del Consejo de Conservaci\u00f3n de Sonoma Land Trust est\u00e1 dando pasos importantes en\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/sonomalandtrust.org\/es\/blog\/julio-2024-enews\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Julio 2024 eNews &#8212; Sonoma Land Trust\" \/>\n<meta property=\"og:description\" content=\"Lo que dicen hoy los cient\u00edficos del ma\u00f1ana El programa para adolescentes del Consejo de Conservaci\u00f3n de Sonoma Land Trust est\u00e1 dando pasos importantes en\" \/>\n<meta property=\"og:url\" content=\"https:\/\/sonomalandtrust.org\/es\/blog\/julio-2024-enews\/\" \/>\n<meta property=\"og:site_name\" content=\"Sonoma Land Trust\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/www.facebook.com\/Sonoma-Land-Trust\/\" \/>\n<meta property=\"article:published_time\" content=\"2024-07-02T06:50:26+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/slt-2026.eclipse-dev.com\/wp-content\/uploads\/2024\/07\/school-children-exploring-nature-binoculars.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1800\" \/>\n\t<meta property=\"og:image:height\" content=\"1200\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"eclipse\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"15 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/sonomalandtrust.org\\\/es\\\/blog\\\/julio-2024-enews\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/sonomalandtrust.org\\\/es\\\/blog\\\/julio-2024-enews\\\/\"},\"author\":{\"name\":\"eclipse\",\"@id\":\"https:\\\/\\\/slt-2026.eclipse-dev.com\\\/#\\\/schema\\\/person\\\/c289b2019a1bd6706f93278c6def96b7\"},\"headline\":\"Julio 2024 eNews\",\"datePublished\":\"2024-07-02T06:50:26+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/sonomalandtrust.org\\\/es\\\/blog\\\/julio-2024-enews\\\/\"},\"wordCount\":3088,\"publisher\":{\"@id\":\"https:\\\/\\\/slt-2026.eclipse-dev.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/sonomalandtrust.org\\\/es\\\/blog\\\/julio-2024-enews\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/sonomalandtrust.org\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/school-children-exploring-nature-binoculars.jpg\",\"articleSection\":[\"eNoticias\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/sonomalandtrust.org\\\/es\\\/blog\\\/julio-2024-enews\\\/\",\"url\":\"https:\\\/\\\/sonomalandtrust.org\\\/es\\\/blog\\\/julio-2024-enews\\\/\",\"name\":\"Julio 2024 eNews &#8212; Sonoma Land Trust\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/slt-2026.eclipse-dev.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/sonomalandtrust.org\\\/es\\\/blog\\\/julio-2024-enews\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/sonomalandtrust.org\\\/es\\\/blog\\\/julio-2024-enews\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/sonomalandtrust.org\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/school-children-exploring-nature-binoculars.jpg\",\"datePublished\":\"2024-07-02T06:50:26+00:00\",\"description\":\"Lo que dicen hoy los cient\u00edficos del ma\u00f1ana El programa para adolescentes del Consejo de Conservaci\u00f3n de Sonoma Land Trust est\u00e1 dando pasos importantes en\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/sonomalandtrust.org\\\/es\\\/blog\\\/julio-2024-enews\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/sonomalandtrust.org\\\/es\\\/blog\\\/julio-2024-enews\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/sonomalandtrust.org\\\/es\\\/blog\\\/julio-2024-enews\\\/#primaryimage\",\"url\":\"https:\\\/\\\/sonomalandtrust.org\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/school-children-exploring-nature-binoculars.jpg\",\"contentUrl\":\"https:\\\/\\\/sonomalandtrust.org\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/school-children-exploring-nature-binoculars.jpg\",\"width\":1800,\"height\":1200,\"caption\":\"Escolares miran el agua con prism\u00e1ticos\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/sonomalandtrust.org\\\/es\\\/blog\\\/julio-2024-enews\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/sonomalandtrust.org\\\/es\\\/inicio\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Julio 2024 eNews\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/slt-2026.eclipse-dev.com\\\/#website\",\"url\":\"https:\\\/\\\/slt-2026.eclipse-dev.com\\\/\",\"name\":\"Sonoma Land Trust\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/slt-2026.eclipse-dev.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/slt-2026.eclipse-dev.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/slt-2026.eclipse-dev.com\\\/#organization\",\"name\":\"Fondo de Tierras de Sonoma\",\"url\":\"https:\\\/\\\/slt-2026.eclipse-dev.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/slt-2026.eclipse-dev.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/sonomalandtrust.org\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/slt-logo.png\",\"contentUrl\":\"https:\\\/\\\/sonomalandtrust.org\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/slt-logo.png\",\"width\":549,\"height\":333,\"caption\":\"Fondo de Tierras de Sonoma\"},\"image\":{\"@id\":\"https:\\\/\\\/slt-2026.eclipse-dev.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/www.facebook.com\\\/Sonoma-Land-Trust\\\/\",\"https:\\\/\\\/www.instagram.com\\\/sonomalandtrust\\\/\",\"https:\\\/\\\/bsky.app\\\/profile\\\/sonomalandtrust.bsky.social\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/SonomaLandTrust\\\/\",\"http:\\\/\\\/www.linkedin.com\\\/company\\\/1090048?trk=tyah\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/slt-2026.eclipse-dev.com\\\/#\\\/schema\\\/person\\\/c289b2019a1bd6706f93278c6def96b7\",\"name\":\"eclipse\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a57eb78d56d01cafd540f163cbd4c579fb8c9fffb50c37d90cc94108dbdf7a0e?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a57eb78d56d01cafd540f163cbd4c579fb8c9fffb50c37d90cc94108dbdf7a0e?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a57eb78d56d01cafd540f163cbd4c579fb8c9fffb50c37d90cc94108dbdf7a0e?s=96&d=mm&r=g\",\"caption\":\"eclipse\"},\"sameAs\":[\"http:\\\/\\\/sonomalandtrust.org\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Julio 2024 eNews &#8212; Sonoma Land Trust","description":"Lo que dicen hoy los cient\u00edficos del ma\u00f1ana El programa para adolescentes del Consejo de Conservaci\u00f3n de Sonoma Land Trust est\u00e1 dando pasos importantes en","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/sonomalandtrust.org\/es\/blog\/julio-2024-enews\/","og_locale":"es_ES","og_type":"article","og_title":"Julio 2024 eNews &#8212; Sonoma Land Trust","og_description":"Lo que dicen hoy los cient\u00edficos del ma\u00f1ana El programa para adolescentes del Consejo de Conservaci\u00f3n de Sonoma Land Trust est\u00e1 dando pasos importantes en","og_url":"https:\/\/sonomalandtrust.org\/es\/blog\/julio-2024-enews\/","og_site_name":"Sonoma Land Trust","article_publisher":"http:\/\/www.facebook.com\/Sonoma-Land-Trust\/","article_published_time":"2024-07-02T06:50:26+00:00","og_image":[{"width":1800,"height":1200,"url":"https:\/\/slt-2026.eclipse-dev.com\/wp-content\/uploads\/2024\/07\/school-children-exploring-nature-binoculars.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Written by":"eclipse","Est. reading time":"15 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/sonomalandtrust.org\/es\/blog\/julio-2024-enews\/#article","isPartOf":{"@id":"https:\/\/sonomalandtrust.org\/es\/blog\/julio-2024-enews\/"},"author":{"name":"eclipse","@id":"https:\/\/slt-2026.eclipse-dev.com\/#\/schema\/person\/c289b2019a1bd6706f93278c6def96b7"},"headline":"Julio 2024 eNews","datePublished":"2024-07-02T06:50:26+00:00","mainEntityOfPage":{"@id":"https:\/\/sonomalandtrust.org\/es\/blog\/julio-2024-enews\/"},"wordCount":3088,"publisher":{"@id":"https:\/\/slt-2026.eclipse-dev.com\/#organization"},"image":{"@id":"https:\/\/sonomalandtrust.org\/es\/blog\/julio-2024-enews\/#primaryimage"},"thumbnailUrl":"https:\/\/sonomalandtrust.org\/wp-content\/uploads\/2024\/07\/school-children-exploring-nature-binoculars.jpg","articleSection":["eNoticias"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/sonomalandtrust.org\/es\/blog\/julio-2024-enews\/","url":"https:\/\/sonomalandtrust.org\/es\/blog\/julio-2024-enews\/","name":"Julio 2024 eNews &#8212; Sonoma Land Trust","isPartOf":{"@id":"https:\/\/slt-2026.eclipse-dev.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/sonomalandtrust.org\/es\/blog\/julio-2024-enews\/#primaryimage"},"image":{"@id":"https:\/\/sonomalandtrust.org\/es\/blog\/julio-2024-enews\/#primaryimage"},"thumbnailUrl":"https:\/\/sonomalandtrust.org\/wp-content\/uploads\/2024\/07\/school-children-exploring-nature-binoculars.jpg","datePublished":"2024-07-02T06:50:26+00:00","description":"Lo que dicen hoy los cient\u00edficos del ma\u00f1ana El programa para adolescentes del Consejo de Conservaci\u00f3n de Sonoma Land Trust est\u00e1 dando pasos importantes en","breadcrumb":{"@id":"https:\/\/sonomalandtrust.org\/es\/blog\/julio-2024-enews\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/sonomalandtrust.org\/es\/blog\/julio-2024-enews\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/sonomalandtrust.org\/es\/blog\/julio-2024-enews\/#primaryimage","url":"https:\/\/sonomalandtrust.org\/wp-content\/uploads\/2024\/07\/school-children-exploring-nature-binoculars.jpg","contentUrl":"https:\/\/sonomalandtrust.org\/wp-content\/uploads\/2024\/07\/school-children-exploring-nature-binoculars.jpg","width":1800,"height":1200,"caption":"Escolares miran el agua con prism\u00e1ticos"},{"@type":"BreadcrumbList","@id":"https:\/\/sonomalandtrust.org\/es\/blog\/julio-2024-enews\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/sonomalandtrust.org\/es\/inicio\/"},{"@type":"ListItem","position":2,"name":"Julio 2024 eNews"}]},{"@type":"WebSite","@id":"https:\/\/slt-2026.eclipse-dev.com\/#website","url":"https:\/\/slt-2026.eclipse-dev.com\/","name":"Sonoma Land Trust","description":"","publisher":{"@id":"https:\/\/slt-2026.eclipse-dev.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/slt-2026.eclipse-dev.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/slt-2026.eclipse-dev.com\/#organization","name":"Fondo de Tierras de Sonoma","url":"https:\/\/slt-2026.eclipse-dev.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/slt-2026.eclipse-dev.com\/#\/schema\/logo\/image\/","url":"https:\/\/sonomalandtrust.org\/wp-content\/uploads\/2025\/10\/slt-logo.png","contentUrl":"https:\/\/sonomalandtrust.org\/wp-content\/uploads\/2025\/10\/slt-logo.png","width":549,"height":333,"caption":"Fondo de Tierras de Sonoma"},"image":{"@id":"https:\/\/slt-2026.eclipse-dev.com\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/www.facebook.com\/Sonoma-Land-Trust\/","https:\/\/www.instagram.com\/sonomalandtrust\/","https:\/\/bsky.app\/profile\/sonomalandtrust.bsky.social","https:\/\/www.youtube.com\/user\/SonomaLandTrust\/","http:\/\/www.linkedin.com\/company\/1090048?trk=tyah"]},{"@type":"Person","@id":"https:\/\/slt-2026.eclipse-dev.com\/#\/schema\/person\/c289b2019a1bd6706f93278c6def96b7","name":"eclipse","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/a57eb78d56d01cafd540f163cbd4c579fb8c9fffb50c37d90cc94108dbdf7a0e?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a57eb78d56d01cafd540f163cbd4c579fb8c9fffb50c37d90cc94108dbdf7a0e?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a57eb78d56d01cafd540f163cbd4c579fb8c9fffb50c37d90cc94108dbdf7a0e?s=96&d=mm&r=g","caption":"eclipse"},"sameAs":["http:\/\/sonomalandtrust.org"]}]}},"_links":{"self":[{"href":"https:\/\/sonomalandtrust.org\/es\/wp-json\/wp\/v2\/posts\/14134","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sonomalandtrust.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sonomalandtrust.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sonomalandtrust.org\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/sonomalandtrust.org\/es\/wp-json\/wp\/v2\/comments?post=14134"}],"version-history":[{"count":0,"href":"https:\/\/sonomalandtrust.org\/es\/wp-json\/wp\/v2\/posts\/14134\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sonomalandtrust.org\/es\/wp-json\/wp\/v2\/media\/14140"}],"wp:attachment":[{"href":"https:\/\/sonomalandtrust.org\/es\/wp-json\/wp\/v2\/media?parent=14134"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sonomalandtrust.org\/es\/wp-json\/wp\/v2\/categories?post=14134"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sonomalandtrust.org\/es\/wp-json\/wp\/v2\/tags?post=14134"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}